{"id":1445,"date":"2026-04-22T00:00:00","date_gmt":"2026-04-22T00:00:00","guid":{"rendered":"https:\/\/escolapios.cl\/wp\/preestreno-serie-quique-h-detective\/"},"modified":"2026-06-02T17:39:28","modified_gmt":"2026-06-02T17:39:28","slug":"preestreno-serie-quique-h-detective","status":"publish","type":"post","link":"https:\/\/escolapios.cl\/wp\/preestreno-serie-quique-h-detective\/","title":{"rendered":"PREESTRENO SERIE \u201cQUIQUE H DETECTIVE\u201d"},"content":{"rendered":"<p><em>Celebrando el D\u00eda del Libro con el legado de \u00abQuique H Detective\u00bb<\/em><\/p>\n<p>Colegio Calasanz<\/p>\n<p>22 de Abril 2026<\/p>\n<p>Hace pocos d\u00edas, en nuestro colegio Calasanz, se llev\u00f3 a cabo el preestreno de la serie de televisi\u00f3n \u201cQuique H detective\u201d, basada en el libro del mismo nombre del fallecido autor Sergio G\u00f3mez Mardones.<\/p>\n<p>Al evento asistieron estudiantes de 5\u00b0 y 6\u00b0 b\u00e1sico, junto a sus profesores y los principales directivos del establecimiento, los cuales pudieron disfrutar del primer cap\u00edtulo de la serie.<\/p>\n<p>Como invitados especiales, estuvieron presentes los hijos del autor, representantes de Ediciones SM, de la Corporaci\u00f3n Municipal de \u00d1u\u00f1oa, el equipo organizador de la serie, el CNTV y los actores que forman parte del elenco.<\/p>\n<p>Durante la actividad, el Director General de SM, Francisco Tepper, entreg\u00f3 un emotivo mensaje en el que destac\u00f3 la relaci\u00f3n del autor con la editorial durante casi 20 a\u00f1os. Gracias a sus publicaciones, Sergio G\u00f3mez recibi\u00f3 en dos oportunidades el premio \u201cBarco de Vapor\u201d por sus libros \u201cEl canario polaco\u201d y \u201cLos incre\u00edbles poderes del se\u00f1or Tanaca\u201d. Para Tepper, fue un orgullo haber compartido con el autor.<\/p>\n<p>Por su parte, la Directora del colegio Calasanz, se\u00f1ora Sandra Mancilla, hizo referencia al lema institucional \u201cPiedad y Letras\u201d, se\u00f1alando: \u201cHoy hablamos de letras\u201d. Adem\u00e1s, destac\u00f3 que muchas generaciones de estudiantes han le\u00eddo y disfrutado \u201cQuique H detective\u201d y expres\u00f3 el orgullo de participar en esta actividad en el marco de la celebraci\u00f3n de los 75 a\u00f1os del colegio.<\/p>\n<p>Este preestreno se enmarca en las actividades del D\u00eda del Libro, reafirmando el compromiso del colegio con el fomento lector y la valoraci\u00f3n de la literatura como una herramienta fundamental en la formaci\u00f3n integral de sus estudiantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Celebrando el D\u00eda del Libro con el legado de \u00abQuique H Detective\u00bb Colegio Calasanz 22 de Abril 2026 Hace pocos d\u00edas, en nuestro colegio Calasanz, se llev\u00f3 a cabo el preestreno de la serie de televisi\u00f3n \u201cQuique H detective\u201d, basada en el libro del mismo nombre del fallecido autor Sergio G\u00f3mez Mardones. Al evento asistieron [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/posts\/1445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/comments?post=1445"}],"version-history":[{"count":2,"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/posts\/1445\/revisions"}],"predecessor-version":[{"id":1579,"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/posts\/1445\/revisions\/1579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/media\/1446"}],"wp:attachment":[{"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/media?parent=1445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/categories?post=1445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escolapios.cl\/wp\/wp-json\/wp\/v2\/tags?post=1445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}